{"id":4972,"date":"2026-05-13T17:17:43","date_gmt":"2026-05-13T17:17:43","guid":{"rendered":"https:\/\/www.lumaltik.org\/2026\/05\/comunicado-de-europazapatista-sobre-los-ataques-al-cipog-ez\/"},"modified":"2026-05-13T17:19:31","modified_gmt":"2026-05-13T17:19:31","slug":"comunicado-de-europazapatista-sobre-los-ataques-al-cipog-ez","status":"publish","type":"post","link":"https:\/\/www.lumaltik.org\/eu\/2026\/05\/comunicado-de-europazapatista-sobre-los-ataques-al-cipog-ez\/","title":{"rendered":"Comunicado de EuropaZapatista sobre los ataques al CIPOG-EZ"},"content":{"rendered":"\n<p><a><\/a> Desde la red de EuropaZapatista, denunciamos en\u00e9rgicamente el ataque que los pueblos y comunidades ind\u00edgenas del CIPOG-EZ, en Guerrero, M\u00e9xico, est\u00e1n sufriendo por parte del grupo criminal \u201cLos Ardillos\u201d.<\/p>\n\n\n\n<p>Esta situaci\u00f3n, que viene desde lejos y cuenta con un saldo de 76 compa\u00f1eros y compa\u00f1eras asesinados y 25 desaparecidos, se ha vuelto a recrudecer en los primeros d\u00edas de mayo con ataques a las comunidades de Tula, Xicotl\u00e1n, Acahuehuetl\u00e1n y Alcozac\u00e1n; una se\u00f1ora de Xicotl\u00e1n fue herida de bala el d\u00eda 8 de mayo, y el 9, este grupo narco-paramilitar, que act\u00faa con total impunidad bajo la protecci\u00f3n del Ej\u00e9rcito y el gobierno federal, lanz\u00f3 drones sobre la comunidad de Tula y establecieron una trinchera a 200 m de una base militar cerca de la comunidad, al tiempo que la atacan desde las monta\u00f1as a su alrededor. Ese mismo d\u00eda 9, las comunidades agredidas han sido bombardeadas durante m\u00e1s de 8 horas.<\/p>\n\n\n\n<p>Mientras esto ocurre, Guardia Nacional y Polic\u00eda Estatal, coordinados con el Ej\u00e9rcito Mexicano, integrantes de la Base de Operaciones Interinstitucionales (BOI), se hicieron presentes en las comunidades agredidas, pero solo para tomarse fotos, sin realizar acciones reales que garantizaran la seguridad.<\/p>\n\n\n\n<p>Desde la Europa Insumisa:<\/p>\n\n\n\n<p><strong>Denunciamos <\/strong>la complicidad y responsabilidad de los tres niveles de gobierno, que protegen a los criminales como parte de una estrategia contra las comunidades ind\u00edgenas que se organizan y resisten en defensa de su territorio, su autonom\u00eda y la vida.<\/p>\n\n\n\n<p><strong>Denunciamos <\/strong>la situaci\u00f3n de guerra que, en M\u00e9xico, viven las comunidades ind\u00edgenas que se atreven a resistir.<\/p>\n\n\n\n<p><strong>Exigimos <\/strong>el cese inmediato de los actos de violencia contra esas comunidades, y en concreto, contra el CIPOG-EZ.<\/p>\n\n\n\n<p><strong>Exigimos<\/strong> el fin de la impunidad de los grupos narco-paramilitares y el apoyo, por acci\u00f3n u omisi\u00f3n, de los poderes del Estado.<\/p>\n\n\n\n<p>Por la red de EuropaZapatista,<\/p>\n\n\n\n<p>20ZLN. Italia<\/p>\n\n\n\n<p>Asamblea Libertaria Autoorganizada Paliacate Zapatista. Grecia<\/p>\n\n\n\n<p>Assemblea de Solidaritat amb M\u00e8xic-ASMEX. Pa\u00eds Valenci\u00e0, Estado Espa\u00f1ol<\/p>\n\n\n\n<p>Associaci\u00f3 Solidaria Caf\u00e8 Rebeld\u00eda-Infoespai. Barcelona, Catalunya<\/p>\n\n\n\n<p>Associazione Ya Basta! \u00cad\u00ee bese. Italia<\/p>\n\n\n\n<p>Batec Zapatista. Barcelona, Catalu\u00f1a<\/p>\n\n\n\n<p>Caf\u00e9 Libertad Kollektiv. Hamburgo, Alemania<\/p>\n\n\n\n<p>Cafez. Lieja, B\u00e9lgica<\/p>\n\n\n\n<p>Cal Cases. Catalu\u00f1a<\/p>\n\n\n\n<p>Caracoleras de Olba. Olba, Teruel, Estado Espa\u00f1ol<\/p>\n\n\n\n<p>CAREA e.V. Alemania<\/p>\n\n\n\n<p>Centro de Documentaci\u00f3n sobre Zapatismo. Cedoz. Estado Espa\u00f1ol<\/p>\n\n\n\n<p>Colectivo Armadillo Suomi. Finlandia<\/p>\n\n\n\n<p>Colectivo Calendario Zapatista. Grecia<\/p>\n\n\n\n<p>Colectivo Ramona. Chipre<\/p>\n\n\n\n<p>Collettivo Zapatista Lugano. Suiza<\/p>\n\n\n\n<p>Comitato Chiapas Maribel. B\u00e9rgamo, Italia<\/p>\n\n\n\n<p>Comit\u00e9 de solidaridad con Latinoam\u00e9rica (LAG) &#8211; Chiapasgruppa LAG. Oslo, Noruega<\/p>\n\n\n\n<p>Confederaci\u00f3n General del Trabajo &#8211; CGT. Estado Espa\u00f1ol<\/p>\n\n\n\n<p>Cooperazione Rebelde Napoli. Italia<\/p>\n\n\n\n<p>CSPCL, Par\u00eds, Francia.<\/p>\n\n\n\n<p>Espoir Chiapas. Francia<\/p>\n\n\n\n<p>Frankfurt International. Alemania<\/p>\n\n\n\n<p>Gira Zapatista Holanda. Holanda<\/p>\n\n\n\n<p>Grupo M\u00e9xico del Foro Internacional. Dinamarca<\/p>\n\n\n\n<p>Gruppe B.A.S.T.A. Munster, Alemania<\/p>\n\n\n\n<p>Kaffeekollektiv Aroma Zapatista, Hamburgo<\/p>\n\n\n\n<p>Lumaltik Herriak. Pa\u00eds Vasco<\/p>\n\n\n\n<p>Mujeres y Disidencias de la Sexta en la Otra Europa y Abya Yala.<\/p>\n\n\n\n<p>Mut Vitz 13. Marsella, Francia<\/p>\n\n\n\n<p>Mut Vitz 31. Toulouse, Francia<\/p>\n\n\n\n<p>Mut Vitz 34. Francia<\/p>\n\n\n\n<p>Nodo Solidale Roma. Italia<\/p>\n\n\n\n<p>Pallasos en Rebeld\u00eda. Estado Espa\u00f1ol<\/p>\n\n\n\n<p>Quinoa. B\u00e9lgica<\/p>\n\n\n\n<p>Red de Rebeli\u00f3n. Alemania<\/p>\n\n\n\n<p>Red Ya-Basta-Netz. Alemania<\/p>\n\n\n\n<p>Silbo Zapatista. Estado Espa\u00f1ol<\/p>\n\n\n\n<p>Solidaridad Directa Chiapas. Suiza<\/p>\n\n\n\n<p>Tatawelo. Italia<\/p>\n\n\n\n<p>Terra Insumisa Alcamo \/ Sicilia Sud Globale. Sicilia, Italia<\/p>\n\n\n\n<p>TxiapasEKIN. Pa\u00eds Vasco<\/p>\n\n\n\n<p>Union Syndicale Solidaires<\/p>\n\n\n\n<p>USI 1912 Italia e Usicons aps Italia<\/p>\n\n\n\n<p>Y Retiemble. Madrid, Estado Espa\u00f1ol<\/p>\n\n\n\n<p>Ya Basta Bolonia. Italia<\/p>\n\n\n\n<p>Ya Basta Milano. Italia<\/p>\n\n\n\n<p>Ya-Basta-Netz, Alemania<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde la red de EuropaZapatista, denunciamos en\u00e9rgicamente el ataque que los pueblos y comunidades ind\u00edgenas del CIPOG-EZ, en Guerrero, M\u00e9xico, est\u00e1n sufriendo por parte del grupo criminal \u201cLos Ardillos\u201d. Esta situaci\u00f3n, que viene desde lejos y cuenta con un saldo de 76 compa\u00f1eros y compa\u00f1eras asesinados y 25 desaparecidos, se ha vuelto a recrudecer en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4970,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-4972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicado-eu"],"blocksy_meta":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lumaltik.org\/eu\/wp-json\/wp\/v2\/posts\/4972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lumaltik.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lumaltik.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lumaltik.org\/eu\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lumaltik.org\/eu\/wp-json\/wp\/v2\/comments?post=4972"}],"version-history":[{"count":1,"href":"https:\/\/www.lumaltik.org\/eu\/wp-json\/wp\/v2\/posts\/4972\/revisions"}],"predecessor-version":[{"id":4973,"href":"https:\/\/www.lumaltik.org\/eu\/wp-json\/wp\/v2\/posts\/4972\/revisions\/4973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lumaltik.org\/eu\/wp-json\/wp\/v2\/media\/4970"}],"wp:attachment":[{"href":"https:\/\/www.lumaltik.org\/eu\/wp-json\/wp\/v2\/media?parent=4972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lumaltik.org\/eu\/wp-json\/wp\/v2\/categories?post=4972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lumaltik.org\/eu\/wp-json\/wp\/v2\/tags?post=4972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}